{"id":3745,"date":"2022-12-01T16:58:58","date_gmt":"2022-12-01T15:58:58","guid":{"rendered":"http:\/\/archiviostorico.comuneacquapendente.it\/?post_type=portfolio&#038;p=3745"},"modified":"2022-12-01T16:58:58","modified_gmt":"2022-12-01T15:58:58","slug":"af000687-cb2-38-7-acquapendente-carnevale-1963-il-circo-di-topolino-particolare","status":"publish","type":"portfolio","link":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/portfolio\/af000687-cb2-38-7-acquapendente-carnevale-1963-il-circo-di-topolino-particolare\/","title":{"rendered":"AF000687 \/ CB2.38.7 Acquapendente &#8211; Carnevale 1963 -Il Circo di Topolino &#8211; particolare"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3746,"menu_order":0,"template":"elementor_theme","meta":{"footnotes":""},"portfolio-cat":[23,25,50],"portfolio-tag":[18,86,85,84],"portfolio-filter":[14],"class_list":["post-3745","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-cat-acquapendente","portfolio-cat-carnevale","portfolio-cat-carnevali-dopoguerra","portfolio-tag-acquapendente","portfolio-tag-aziende","portfolio-tag-palazzi","portfolio-tag-varie","portfolio-filter-archivio-fotografico"],"_links":{"self":[{"href":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/wp-json\/wp\/v2\/portfolio\/3745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":1,"href":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/wp-json\/wp\/v2\/portfolio\/3745\/revisions"}],"predecessor-version":[{"id":3747,"href":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/wp-json\/wp\/v2\/portfolio\/3745\/revisions\/3747"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/wp-json\/wp\/v2\/media\/3746"}],"wp:attachment":[{"href":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/wp-json\/wp\/v2\/media?parent=3745"}],"wp:term":[{"taxonomy":"portfolio-cat","embeddable":true,"href":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/wp-json\/wp\/v2\/portfolio-cat?post=3745"},{"taxonomy":"portfolio-tag","embeddable":true,"href":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/wp-json\/wp\/v2\/portfolio-tag?post=3745"},{"taxonomy":"portfolio-filter","embeddable":true,"href":"http:\/\/archiviostorico.comuneacquapendente.it\/index.php\/wp-json\/wp\/v2\/portfolio-filter?post=3745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}